{"id":426,"date":"2023-07-10T07:07:01","date_gmt":"2023-07-10T07:07:01","guid":{"rendered":"https:\/\/demos.eaglevisionit.com\/travel-ride\/?page_id=426"},"modified":"2023-07-10T07:07:01","modified_gmt":"2023-07-10T07:07:01","slug":"home","status":"publish","type":"page","link":"https:\/\/demos.eaglevisionit.com\/travel-ride\/","title":{"rendered":"Home"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-426","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/demos.eaglevisionit.com\/travel-ride\/wp-json\/wp\/v2\/pages\/426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demos.eaglevisionit.com\/travel-ride\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demos.eaglevisionit.com\/travel-ride\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demos.eaglevisionit.com\/travel-ride\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demos.eaglevisionit.com\/travel-ride\/wp-json\/wp\/v2\/comments?post=426"}],"version-history":[{"count":1,"href":"https:\/\/demos.eaglevisionit.com\/travel-ride\/wp-json\/wp\/v2\/pages\/426\/revisions"}],"predecessor-version":[{"id":427,"href":"https:\/\/demos.eaglevisionit.com\/travel-ride\/wp-json\/wp\/v2\/pages\/426\/revisions\/427"}],"wp:attachment":[{"href":"https:\/\/demos.eaglevisionit.com\/travel-ride\/wp-json\/wp\/v2\/media?parent=426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}